{"id":1157,"date":"2013-06-18T10:18:00","date_gmt":"2013-04-18T10:18:00","guid":{"rendered":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/?p=1157"},"modified":"2013-03-18T11:32:21","modified_gmt":"2013-03-18T11:32:21","slug":"malta-2-semanas-ela","status":"publish","type":"post","link":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/2013\/06\/18\/malta-2-semanas-ela\/","title":{"rendered":"Malta &#8211; 2 semanas ELA"},"content":{"rendered":"<blockquote><p>Hola,<\/p>\n<p>Acabo de regresar de pasar 15 d\u00edas en Malta y tengo que decir que ha sido una experiencia inolvidable.<\/p>\n<p>He estado con una amiga en Sliema donde hemos tenido la suerte de caer en una familia fant\u00e1stica. En la familia estaba la madre y dos chicas de nuestra edad m\u00e1s o menos, el ambiente en la casa ha sido lo mejor.<br \/>\nRespecto a las clases nos hemos quedado solamente 2 semanas y no hemos tenido el tiempo de progresar mucho, pero hemos podido reforzar nuestros conocimientos \u00a0y bases en el idioma, por lo que el oral lo hemos mejorado mucho, ahora hablo con m\u00e1s fluidez .<\/p>\n<p>En la escuela todo el mundo ha sido amable y muy simp\u00e1tico, el ambiente es genial y hemos conocido estudiantes de diferentes pa\u00edses\u00a0 y hemos hecho amistades.<br \/>\nEn conclusi\u00f3n, he pasado dos semanas magn\u00edficas yme encantar\u00eda volver a Malta, pero creo que es mejor quedarse m\u00e1s de 2 semanas<br \/>\n<em>Ana- 17 a\u00f1os- Malta<\/em><\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1158\" title=\"_montage-photo-temoignage\" src=\"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-content\/uploads\/2009\/09\/montage-photo-temoignage.jpg\" alt=\"_montage-photo-temoignage\" width=\"630\" height=\"130\" srcset=\"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-content\/uploads\/2009\/09\/montage-photo-temoignage.jpg 630w, http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-content\/uploads\/2009\/09\/montage-photo-temoignage-300x61.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hola, Acabo de regresar de pasar 15 d\u00edas en Malta y tengo que decir que ha sido una experiencia inolvidable. He estado con una amiga en Sliema donde hemos tenido la suerte de caer en una familia fant\u00e1stica. En la <a class=\"more-link\" href=\"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/2013\/06\/18\/malta-2-semanas-ela\/\">Seguir leyendo <span class=\"screen-reader-text\">  Malta &#8211; 2 semanas ELA<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1157","post","type-post","status-publish","format-standard","hentry","category-vuestra-experiencia"],"_links":{"self":[{"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/posts\/1157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/comments?post=1157"}],"version-history":[{"count":5,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/posts\/1157\/revisions"}],"predecessor-version":[{"id":1161,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/posts\/1157\/revisions\/1161"}],"wp:attachment":[{"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/media?parent=1157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/categories?post=1157"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/tags?post=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}