{"id":1077,"date":"2013-06-18T10:18:00","date_gmt":"2013-04-18T10:18:00","guid":{"rendered":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/?p=1077"},"modified":"2013-03-18T11:12:59","modified_gmt":"2013-03-18T11:12:59","slug":"cursos-en-casa-del-profesor-en-londres","status":"publish","type":"post","link":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/2013\/06\/18\/cursos-en-casa-del-profesor-en-londres\/","title":{"rendered":"Cursos en casa del profesor en Londres"},"content":{"rendered":"<blockquote><p>Al principio he hablado \u00a0con el profesor sobre mis expectativas y ella se ha adaptado muy bien a mi personalidad y a los progresos que yo esperaba.\u00a0Hemos trabajado mucho en el acento porque yo lo ped\u00ed y todos los d\u00edas hemos empezado por la lectura del peri\u00f3dico.\u00a0He sido muy bien recibido en la familia de mi profesor. El alojamiento ha sido de gran calidad. Adem\u00e1s, han hecho muchos esfuerzos por cocinar a mi gusto.\u00a0Me he integrado muy bien a la vida de la casa y me han propuesto muchas actividades.\u00a0He apreciado mucho que al comienzo del curso los organizadores me han llamado para ver c\u00f3mo me iba en el curso y en la casa.Estoy muy satisfecho en general y recomiendo este tipo de curso.<\/p><\/blockquote>\n<p><span style=\"color: #e0027a;\"><em>Mar\u00eda &#8211; 56 a\u00f1os- <a href=\"http:\/\/www.activa-idiomas.es\/es\/inmersion-en-casa-del-profesor-en-inglaterra\/londres-region\/hli-home-language-international\/cursos-en-casa-del-profesor\/\" target=\"_blank\">Curso en casa del profesor en la regi\u00f3n de\u00a0Londres<\/a><\/em><\/span><span style=\"color: #e0027a;\"><em> <\/em><\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1092\" title=\"region-londres-prof61\" src=\"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-content\/uploads\/2009\/07\/region-londres-prof61.jpg\" alt=\"region-londres-prof61\" width=\"630\" height=\"130\" srcset=\"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-content\/uploads\/2009\/07\/region-londres-prof61.jpg 630w, http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-content\/uploads\/2009\/07\/region-londres-prof61-300x61.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Al principio he hablado \u00a0con el profesor sobre mis expectativas y ella se ha adaptado muy bien a mi personalidad y a los progresos que yo esperaba.\u00a0Hemos trabajado mucho en el acento porque yo lo ped\u00ed y todos los d\u00edas <a class=\"more-link\" href=\"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/2013\/06\/18\/cursos-en-casa-del-profesor-en-londres\/\">Seguir leyendo <span class=\"screen-reader-text\">  Cursos en casa del profesor en Londres<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1077","post","type-post","status-publish","format-standard","hentry","category-vuestra-experiencia"],"_links":{"self":[{"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/posts\/1077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/comments?post=1077"}],"version-history":[{"count":10,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/posts\/1077\/revisions"}],"predecessor-version":[{"id":1102,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/posts\/1077\/revisions\/1102"}],"wp:attachment":[{"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/media?parent=1077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/categories?post=1077"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.blog-cursos-idiomas.es\/cursos-idiomas\/wp-json\/wp\/v2\/tags?post=1077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}